{"id":22613,"date":"2024-07-18T09:58:09","date_gmt":"2024-07-18T08:58:09","guid":{"rendered":"https:\/\/www.smartbuildinglevante.it\/?p=22613"},"modified":"2024-07-18T10:59:35","modified_gmt":"2024-07-18T09:59:35","slug":"i-protagonisti-di-sbl24-inim","status":"publish","type":"post","link":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/","title":{"rendered":"I protagonisti di SBL24: INIM"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22741 size-full alignleft\" src=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg\" alt=\"\" width=\"480\" height=\"252\" srcset=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg 480w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news-240x126.jpg 240w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p><strong><a href=\"https:\/\/www.inim.biz\/\">Inim<\/a><\/strong> \u00e8 un\u2019azienda di produzione che progetta, realizza e commercializza sistemi antincendio e antifurto in Italia e nel mondo.<\/p>\n<p>Inim sceglie di partecipare a Smart Building Levante 2024 con uno dei suo maggiori partner a livello di distribuzione nel Sud Italia: <strong>Digital System s.r.l.<\/strong>, realt\u00e0 consolidata nel settore della sicurezza e dell&#8217;automazione, con sede a Martina Franca (TA) e filiali a Modugno, Lecce, Oria e Casarano.<br \/>\nL\u2019azienda distributore a valore aggiunto che si impegna a semplificare il lavoro degli installatori e migliorare l&#8217;esperienza degli utenti finali, offrendo le nostre soluzioni sicure e di facile utilizzo.<br \/>\nAbbiamo deciso di partecipare a Smart Building Levante 2024 perch\u00e9 riconosciamo in questa manifestazione un\u2019opportunit\u00e0 per presentare le nostre innovazioni e confrontarci con altri leader del settore. Crediamo che SBL24 sia una vetrina strategica per esporre le nostre soluzioni avanzate. Ci aspettiamo di incontrare un pubblico interessato e competente, di scoprire le ultime tendenze del mercato e di ricevere feedback preziosi per migliorare ulteriormente la nostra offerta.<\/p>\n<h3>Quali novit\u00e0 porterete in fiera a Bari?<\/h3>\n<p>Alla fiera di Bari presenteremo una gamma selezionata di prodotti innovativi nel campo della protezione antincendio, della sicurezza, della domotica e dell&#8217;automazione.<\/p>\n<h3>Qual \u00e8 il ruolo del Sud Italia nel contesto dell&#8217;innovazione e dell&#8217;integrazione tecnologica, in tema di home, building &amp; city?<\/h3>\n<p>Per Inim il Sud Italia sta assumendo un ruolo sempre pi\u00f9 rilevante nell&#8217;innovazione e nell&#8217;integrazione tecnologica, specialmente nei settori della domotica, della sicurezza e delle smart cities. Grazie a un crescente interesse per le tecnologie sostenibili e a una forte spinta verso la digitalizzazione, il territorio del Sud Italia \u00e8 diventato un laboratorio ideale per sperimentare e implementare soluzioni avanzate. Siamo orgogliosi di poter partecipare a questa trasformazione e di poter offrire il nostro contributo al progresso tecnologico del Sud Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inim \u00e8 un\u2019azienda di produzione che progetta, realizza e commercializza sistemi antincendio e antifurto in Italia e nel mondo.<\/p>\n","protected":false},"author":26,"featured_media":22741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22613","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I protagonisti di SBL24: INIM &#8212; Smart Building Levante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I protagonisti di SBL24: INIM &#8212; Smart Building Levante\" \/>\n<meta property=\"og:description\" content=\"Inim \u00e8 un\u2019azienda di produzione che progetta, realizza e commercializza sistemi antincendio e antifurto in Italia e nel mondo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/\" \/>\n<meta property=\"og:site_name\" content=\"Smart Building Levante\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-18T08:58:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T09:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ilaria Rebecchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Rebecchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/\"},\"author\":{\"name\":\"Ilaria Rebecchi\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/e2e8185fd78b97454ee9c30f1bc29ca0\"},\"headline\":\"I protagonisti di SBL24: INIM\",\"datePublished\":\"2024-07-18T08:58:09+00:00\",\"dateModified\":\"2024-07-18T09:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/\"},\"wordCount\":304,\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/inim-news.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/\",\"name\":\"I protagonisti di SBL24: INIM &#8212; Smart Building Levante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/inim-news.jpg\",\"datePublished\":\"2024-07-18T08:58:09+00:00\",\"dateModified\":\"2024-07-18T09:59:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/inim-news.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/inim-news.jpg\",\"width\":480,\"height\":252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/i-protagonisti-di-sbl24-inim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I protagonisti di SBL24: INIM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"name\":\"Smart Building Levante\",\"description\":\"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\",\"name\":\"Pentastudio Srl\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"width\":400,\"height\":200,\"caption\":\"Pentastudio Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/e2e8185fd78b97454ee9c30f1bc29ca0\",\"name\":\"Ilaria Rebecchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g\",\"caption\":\"Ilaria Rebecchi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I protagonisti di SBL24: INIM &#8212; Smart Building Levante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/","og_locale":"it_IT","og_type":"article","og_title":"I protagonisti di SBL24: INIM &#8212; Smart Building Levante","og_description":"Inim \u00e8 un\u2019azienda di produzione che progetta, realizza e commercializza sistemi antincendio e antifurto in Italia e nel mondo.","og_url":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/","og_site_name":"Smart Building Levante","article_published_time":"2024-07-18T08:58:09+00:00","article_modified_time":"2024-07-18T09:59:35+00:00","og_image":[{"width":480,"height":252,"url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg","type":"image\/jpeg"}],"author":"Ilaria Rebecchi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ilaria Rebecchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#article","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/"},"author":{"name":"Ilaria Rebecchi","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/e2e8185fd78b97454ee9c30f1bc29ca0"},"headline":"I protagonisti di SBL24: INIM","datePublished":"2024-07-18T08:58:09+00:00","dateModified":"2024-07-18T09:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/"},"wordCount":304,"publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/","url":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/","name":"I protagonisti di SBL24: INIM &#8212; Smart Building Levante","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#primaryimage"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg","datePublished":"2024-07-18T08:58:09+00:00","dateModified":"2024-07-18T09:59:35+00:00","breadcrumb":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#primaryimage","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/07\/inim-news.jpg","width":480,"height":252},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartbuildinglevante.it\/it\/i-protagonisti-di-sbl24-inim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartbuildinglevante.it\/it\/"},{"@type":"ListItem","position":2,"name":"I protagonisti di SBL24: INIM"}]},{"@type":"WebSite","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website","url":"https:\/\/www.smartbuildinglevante.it\/it\/","name":"Smart Building Levante","description":"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO","publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartbuildinglevante.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization","name":"Pentastudio Srl","url":"https:\/\/www.smartbuildinglevante.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","width":400,"height":200,"caption":"Pentastudio Srl"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/e2e8185fd78b97454ee9c30f1bc29ca0","name":"Ilaria Rebecchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a47f3a7e99b0b8cf15abb355216ba1c34549e5c90bcfbdaa29ea7aa72254ebb1?s=96&d=mm&r=g","caption":"Ilaria Rebecchi"}}]}},"_links":{"self":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/22613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/comments?post=22613"}],"version-history":[{"count":7,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/22613\/revisions"}],"predecessor-version":[{"id":22753,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/22613\/revisions\/22753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media\/22741"}],"wp:attachment":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media?parent=22613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/categories?post=22613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/tags?post=22613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}