{"id":25070,"date":"2024-12-13T09:06:40","date_gmt":"2024-12-13T08:06:40","guid":{"rendered":"https:\/\/www.smartbuildinglevante.it\/?p=25070"},"modified":"2025-07-24T10:08:19","modified_gmt":"2025-07-24T09:08:19","slug":"nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti","status":"publish","type":"post","link":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/","title":{"rendered":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti"},"content":{"rendered":"<p><strong>Fiera<\/strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-25075 \" style=\"font-size: 16px;\" src=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/file.png\" alt=\"\" width=\"464\" height=\"272\" srcset=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/file.png 1333w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/file-240x141.png 240w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/file-480x281.png 480w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/file-768x450.png 768w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><strong style=\"font-size: 16px;\">\u00a0Mila<\/strong><strong style=\"font-size: 16px;\">no lavora all\u2019organizzazione a Bari di MIBA Levante, spin-off del grande evento internazionale MIBA \u2013 Milan International Building Alliance dedicato a tecnologie, materiali e soluzioni per la progettazione, costruzione e riqualificazione di edifici e citt\u00e0 e alla transizione ecologica e digitale del costruito.<\/strong><\/p>\n<p><strong>L\u2019annuncio \u00e8 stato dato in occasione della presentazione di MIBA 2025, che si svolger\u00e0 dal 19 al 21 novembre del prossimo anno a Fiera Milano (Rho).<\/strong><\/p>\n<p>L\u2019evento vede contemporaneit\u00e0 e sinergie tra quattro fiere specializzate: <strong>GEE-Global Elevator Exhibition<\/strong>, la fiera della mobilit\u00e0 orizzontale e verticale; <strong>MADE Expo<\/strong>, l\u2019evento leader per il comparto dell\u2019edilizia (che durer\u00e0 un giorno di pi\u00f9 e chiuder\u00e0 il 22 novembre); <strong>Smart Building Expo<\/strong>, la manifestazione dell\u2019integrazione tecnologica per l\u2019edilizia urbanistica (che ha gi\u00e0 uno spin-off barese con Smart Building Levante); e <strong>Sicurezza<\/strong>, la fiera italiana di riferimento nei settori sicurezza e antincendio.<\/p>\n<p>La prima edizione di<strong> MIBA Levante<\/strong> \u2013 che porter\u00e0 sul territorio la medesima tipologia di offerta dell\u2019appuntamento milanese \u2013 si svolger\u00e0 invece nel <strong>novembre 2026 presso la Fiera del Levante<\/strong>, alternandosi dunque all\u2019evento che si tiene negli anni dispari a Fiera Milano.<\/p>\n<p>\u201c<em>Il <strong>mondo del costruito<\/strong> e tutti i comparti indirettamente coinvolti, dalle <strong>tecnologie di sicurezza agli impianti<\/strong>, fino ai <strong>sistemi mobilit\u00e0 interna<\/strong>, devono affrontare la sfida della riqualificazione urbana, che rappresenta al contempo una grande opportunit\u00e0 di business, visto che pi\u00f9 del 70% del valore del mercato \u00e8 legato alle attivit\u00e0 di manutenzione<\/em>\u201d, ha dichiarato <strong>Simona Greco<\/strong>, direttore manifestazioni di Fiera Milano. \u201c<em>MIBA a Fiera Milano il prossimo anno accender\u00e0 i riflettori a <strong>livello nazionale e internazionale<\/strong> su questo scenario. L\u2019iniziativa a Bari sar\u00e0 <strong>un trait-d\u2019union<\/strong> tra le due edizioni di MIBA, ma anche un\u2019occasione di aggiornamento e confronto dedicata ai professionisti e alle aziende del Sud d\u2019Italia, con un focus particolare sulla Puglia, ma anche ai Paesi frontalieri del Mediterraneo. Un segnale concreto della nostra volont\u00e0 di essere presenti su un territorio particolarmente sensibile a queste tematiche di sviluppo<\/em>\u201d.<\/p>\n<p>\u201c<em>Dopo il successo delle tre edizioni di Smart Building Levante a Bari, questa evoluzione, alla quale lavoriamo da circa un anno, era la cosa pi\u00f9 corretta da fare<\/em>\u201d, ha sottolineato <strong>Luca Baldin<\/strong>, project manager di Smart Building Expo e direttore di Smart Building Levante. \u201c<em>Il progetto milanese, infatti, ha il preciso scopo di dotare il Paese di un <strong>evento fieristico di riferimento e di caratura europea<\/strong> per l\u2019<strong>intera filiera industriale e professionale<\/strong> che, da qui al 2050 e oltre, sar\u00e0 impegnata nella transizione digitale ed energetica del patrimonio edilizio italiano. Una transizione che passa sicuramente per <strong>l\u2019elettrificazione e la digitalizzazione<\/strong>, ma che non pu\u00f2 non dialogare strettamente con chi si occupa dell\u2019involucro e della sua sicurezza. Da questo semplice ragionamento, nel 2023 \u00e8 nato MIBA ed era del tutto naturale condividere questo approccio anche a Bari dove, dopo il successo di quest\u2019anno, miriamo nel 2026 a fare un ulteriore grande salto di qualit\u00e0 grazie all\u2019alleanza con Fiera Milano<\/em>\u201d.<\/p>\n<p>In occasione della presentazione di <strong>MIBA 2025 a Milano e dell\u2019annuncio di MIBA Levante 2026 a Bari<\/strong>, Fiera Milano ha anche ufficializzato l\u2019avvio di una collaborazione strutturata con il <strong>Politecnico di Milano<\/strong>, e in particolare con il <strong>Dipartimento di Architettura e Ingegneria delle Costruzioni dell\u2019Ambiente Costruito<\/strong>, per dare vita ad un Osservatorio permanente che avr\u00e0 lo scopo di monitorare il mercato e di disegnare scenari e trend su base scientifica, utili ad orientare le scelte delle aziende del settore e degli operatori professionali.<\/p>\n<p>Una collaborazione di estremo valore, dal momento che gli eventi fieristici di qualit\u00e0 si connotano sempre pi\u00f9 per essere strumenti imprescindibili della filiera stessa e momenti di rappresentazione dei comparti industriali.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/MIBA-Levante.pdf\"><strong>SCARICA IL COMUNICATO STAMPA<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fiera Milano lavora all\u2019organizzazione a Bari di MIBA Levante, spin-off del grande evento internazionale MIBA \u2013 Milan International Building Alliance dedicato a tecnologie, materiali e soluzioni per la progettazione, costruzione e riqualificazione di edifici e citt\u00e0 e alla transizione ecologica e digitale del costruito.<\/p>\n","protected":false},"author":24,"featured_media":25071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25070","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante\" \/>\n<meta property=\"og:description\" content=\"Fiera Milano lavora all\u2019organizzazione a Bari di MIBA Levante, spin-off del grande evento internazionale MIBA \u2013 Milan International Building Alliance dedicato a tecnologie, materiali e soluzioni per la progettazione, costruzione e riqualificazione di edifici e citt\u00e0 e alla transizione ecologica e digitale del costruito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Smart Building Levante\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T08:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T09:08:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pentastudio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pentastudio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/\"},\"author\":{\"name\":\"Pentastudio\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/6cbe44bca5b76d4cd008ff2208e9ecb7\"},\"headline\":\"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti\",\"datePublished\":\"2024-12-13T08:06:40+00:00\",\"dateModified\":\"2025-07-24T09:08:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/\"},\"wordCount\":618,\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mibalevante.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/\",\"name\":\"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mibalevante.jpg\",\"datePublished\":\"2024-12-13T08:06:40+00:00\",\"dateModified\":\"2025-07-24T09:08:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mibalevante.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mibalevante.jpg\",\"width\":480,\"height\":252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"name\":\"Smart Building Levante\",\"description\":\"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\",\"name\":\"Pentastudio Srl\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"width\":400,\"height\":200,\"caption\":\"Pentastudio Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/6cbe44bca5b76d4cd008ff2208e9ecb7\",\"name\":\"Pentastudio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g\",\"caption\":\"Pentastudio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/","og_locale":"it_IT","og_type":"article","og_title":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante","og_description":"Fiera Milano lavora all\u2019organizzazione a Bari di MIBA Levante, spin-off del grande evento internazionale MIBA \u2013 Milan International Building Alliance dedicato a tecnologie, materiali e soluzioni per la progettazione, costruzione e riqualificazione di edifici e citt\u00e0 e alla transizione ecologica e digitale del costruito.","og_url":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/","og_site_name":"Smart Building Levante","article_published_time":"2024-12-13T08:06:40+00:00","article_modified_time":"2025-07-24T09:08:19+00:00","og_image":[{"width":480,"height":252,"url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg","type":"image\/jpeg"}],"author":"Pentastudio","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Pentastudio","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#article","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/"},"author":{"name":"Pentastudio","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/6cbe44bca5b76d4cd008ff2208e9ecb7"},"headline":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti","datePublished":"2024-12-13T08:06:40+00:00","dateModified":"2025-07-24T09:08:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/"},"wordCount":618,"publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/","url":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/","name":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti &#8212; Smart Building Levante","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#primaryimage"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg","datePublished":"2024-12-13T08:06:40+00:00","dateModified":"2025-07-24T09:08:19+00:00","breadcrumb":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#primaryimage","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2024\/12\/mibalevante.jpg","width":480,"height":252},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartbuildinglevante.it\/it\/nasce-miba-levante-a-bari-un-nuovo-evento-su-case-e-citta-intelligenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartbuildinglevante.it\/it\/"},{"@type":"ListItem","position":2,"name":"Nasce MIBA Levante, a Bari un nuovo evento su case e citt\u00e0 intelligenti"}]},{"@type":"WebSite","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website","url":"https:\/\/www.smartbuildinglevante.it\/it\/","name":"Smart Building Levante","description":"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO","publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartbuildinglevante.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization","name":"Pentastudio Srl","url":"https:\/\/www.smartbuildinglevante.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","width":400,"height":200,"caption":"Pentastudio Srl"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/6cbe44bca5b76d4cd008ff2208e9ecb7","name":"Pentastudio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a821ec7a449b5ef551dfb9c35b51981ba81522bb06ec84e381ef5c64e03c7ff7?s=96&d=mm&r=g","caption":"Pentastudio"}}]}},"_links":{"self":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/comments?post=25070"}],"version-history":[{"count":7,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25070\/revisions"}],"predecessor-version":[{"id":25410,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25070\/revisions\/25410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media\/25071"}],"wp:attachment":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media?parent=25070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/categories?post=25070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/tags?post=25070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}