{"id":25119,"date":"2025-01-09T16:19:32","date_gmt":"2025-01-09T15:19:32","guid":{"rendered":"https:\/\/www.smartbuildinglevante.it\/?p=25119"},"modified":"2025-01-13T10:29:22","modified_gmt":"2025-01-13T09:29:22","slug":"successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria","status":"publish","type":"post","link":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/","title":{"rendered":"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#8217;esperienza straordinaria"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-25120 size-large alignleft\" src=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024-480x252.jpg\" alt=\"\" width=\"480\" height=\"252\" srcset=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024-480x252.jpg 480w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024-240x126.jpg 240w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024-768x403.jpg 768w, https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg 1440w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>La partecipazione a <strong>Smart Building Levante<\/strong> si \u00e8 rivelata un\u2019esperienza straordinaria, offrendo opportunit\u00e0 di confronto, aggiornamento e crescita, oltre a uno sguardo su nuovi mercati.<\/p>\n<p><strong>L\u2019evento ha rappresentato un\u2019occasione preziosa per entrare in contatto con professionisti, aziende e istituzioni di grande rilevanza nel contesto locale.<\/strong><\/p>\n<p>L\u2019interesse dimostrato dai visitatori e la qualit\u00e0 delle proposte espositive hanno reso la fiera un palcoscenico ideale per presentare i nostri prodotti e servizi.<\/p>\n<p>Abbiamo avuto il piacere di dialogare con numerose persone, confermando l\u2019importanza di iniziative come questa per promuovere innovazione e sviluppo nel nostro settore.<\/p>\n<p>Il confronto con esperti, l\u2019ascolto delle esigenze dei clienti e l\u2019esplorazione di nuove opportunit\u00e0 di collaborazione hanno reso l\u2019evento estremamente produttivo.<\/p>\n<p>Le relazioni instaurate durante la fiera sono il risultato di un\u2019organizzazione accurata, che ha consentito a ciascuno di noi di trarre il massimo da questa esperienza.<\/p>\n<p>Un sentito ringraziamento va a tutti coloro che hanno visitato il nostro stand.<\/p>\n<p><a href=\"http:\/\/www.intercable-tools.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.intercable-tools.it\/&amp;source=gmail&amp;ust=1736841897230000&amp;usg=AOvVaw3Bt_kHLPYVj66oOaoDupOG\">www.intercable-tools.it<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La partecipazione a Smart Building Levante si \u00e8 rivelata un\u2019esperienza straordinaria, offrendo opportunit\u00e0 di confronto, aggiornamento e crescita, oltre a uno sguardo su nuovi mercati. L\u2019evento ha rappresentato un\u2019occasione preziosa&#8230;<\/p>\n","protected":false},"author":23,"featured_media":25120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25119","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Successo e opportunit\u00e0 alla Fiera del Levante: Un&#039;esperienza straordinaria &#8212; Smart Building Levante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#039;esperienza straordinaria &#8212; Smart Building Levante\" \/>\n<meta property=\"og:description\" content=\"La partecipazione a Smart Building Levante si \u00e8 rivelata un\u2019esperienza straordinaria, offrendo opportunit\u00e0 di confronto, aggiornamento e crescita, oltre a uno sguardo su nuovi mercati. L\u2019evento ha rappresentato un\u2019occasione preziosa...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Smart Building Levante\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-09T15:19:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T09:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Monica Bassan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Monica Bassan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/\"},\"author\":{\"name\":\"Monica Bassan\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/8265bbe72d5f756c3651c292fe306978\"},\"headline\":\"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#8217;esperienza straordinaria\",\"datePublished\":\"2025-01-09T15:19:32+00:00\",\"dateModified\":\"2025-01-13T09:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Newsletter_SMART-BUILDING-Levante-2024.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/\",\"name\":\"Successo e opportunit\u00e0 alla Fiera del Levante: Un'esperienza straordinaria &#8212; Smart Building Levante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Newsletter_SMART-BUILDING-Levante-2024.jpg\",\"datePublished\":\"2025-01-09T15:19:32+00:00\",\"dateModified\":\"2025-01-13T09:29:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Newsletter_SMART-BUILDING-Levante-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Newsletter_SMART-BUILDING-Levante-2024.jpg\",\"width\":1440,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#8217;esperienza straordinaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"name\":\"Smart Building Levante\",\"description\":\"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#organization\",\"name\":\"Pentastudio Srl\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"contentUrl\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pentastudio.png\",\"width\":400,\"height\":200,\"caption\":\"Pentastudio Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smartbuildinglevante.it\\\/it\\\/#\\\/schema\\\/person\\\/8265bbe72d5f756c3651c292fe306978\",\"name\":\"Monica Bassan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g\",\"caption\":\"Monica Bassan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Successo e opportunit\u00e0 alla Fiera del Levante: Un'esperienza straordinaria &#8212; Smart Building Levante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/","og_locale":"it_IT","og_type":"article","og_title":"Successo e opportunit\u00e0 alla Fiera del Levante: Un'esperienza straordinaria &#8212; Smart Building Levante","og_description":"La partecipazione a Smart Building Levante si \u00e8 rivelata un\u2019esperienza straordinaria, offrendo opportunit\u00e0 di confronto, aggiornamento e crescita, oltre a uno sguardo su nuovi mercati. L\u2019evento ha rappresentato un\u2019occasione preziosa...","og_url":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/","og_site_name":"Smart Building Levante","article_published_time":"2025-01-09T15:19:32+00:00","article_modified_time":"2025-01-13T09:29:22+00:00","og_image":[{"width":1440,"height":756,"url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg","type":"image\/jpeg"}],"author":"Monica Bassan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Monica Bassan","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#article","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/"},"author":{"name":"Monica Bassan","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/8265bbe72d5f756c3651c292fe306978"},"headline":"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#8217;esperienza straordinaria","datePublished":"2025-01-09T15:19:32+00:00","dateModified":"2025-01-13T09:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/"},"wordCount":174,"publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/","url":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/","name":"Successo e opportunit\u00e0 alla Fiera del Levante: Un'esperienza straordinaria &#8212; Smart Building Levante","isPartOf":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#primaryimage"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg","datePublished":"2025-01-09T15:19:32+00:00","dateModified":"2025-01-13T09:29:22+00:00","breadcrumb":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#primaryimage","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2025\/01\/Newsletter_SMART-BUILDING-Levante-2024.jpg","width":1440,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartbuildinglevante.it\/it\/successo-e-opportunita-alla-fiera-del-levante-unesperienza-straordinaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartbuildinglevante.it\/it\/"},{"@type":"ListItem","position":2,"name":"Successo e opportunit\u00e0 alla Fiera del Levante: Un&#8217;esperienza straordinaria"}]},{"@type":"WebSite","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#website","url":"https:\/\/www.smartbuildinglevante.it\/it\/","name":"Smart Building Levante","description":"FIERA INTERNAZIONALE DELLA TRANSIZIONE ENERGETICA E DIGITALE DEL PATRIMONIO EDILIZIO DEL MEDITERRANEO","publisher":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartbuildinglevante.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#organization","name":"Pentastudio Srl","url":"https:\/\/www.smartbuildinglevante.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","contentUrl":"https:\/\/www.smartbuildinglevante.it\/wp-content\/uploads\/2021\/09\/pentastudio.png","width":400,"height":200,"caption":"Pentastudio Srl"},"image":{"@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.smartbuildinglevante.it\/it\/#\/schema\/person\/8265bbe72d5f756c3651c292fe306978","name":"Monica Bassan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec97750f16d55bbc230e9a15f6340e53bca3ada3d827278686f71e9bbc74552f?s=96&d=mm&r=g","caption":"Monica Bassan"}}]}},"_links":{"self":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/comments?post=25119"}],"version-history":[{"count":2,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25119\/revisions"}],"predecessor-version":[{"id":25124,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/posts\/25119\/revisions\/25124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media\/25120"}],"wp:attachment":[{"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/media?parent=25119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/categories?post=25119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smartbuildinglevante.it\/it\/wp-json\/wp\/v2\/tags?post=25119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}